{"id":1519,"date":"2025-02-11T09:24:14","date_gmt":"2025-02-11T08:24:14","guid":{"rendered":"https:\/\/www.asimute.uha.fr\/de\/?p=1519"},"modified":"2025-03-17T09:37:20","modified_gmt":"2025-03-17T08:37:20","slug":"interview-prof-ould-abdeslam-koordinator-projekts","status":"publish","type":"post","link":"https:\/\/www.asimute.uha.fr\/de\/2025\/02\/11\/interview-prof-ould-abdeslam-koordinator-projekts\/","title":{"rendered":"Interview mit Prof. Ould-Abdeslam &#8211; Koordinator des ASIMUTE-Projekts"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1519\" class=\"elementor elementor-1519\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8d3ffd7 e-flex e-con-boxed e-con e-parent\" data-id=\"8d3ffd7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2f2a7a0 elementor-widget elementor-widget-global elementor-global-53 elementor-widget-breadcrumbs\" data-id=\"2f2a7a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p id=\"breadcrumbs\"><span><span><a href=\"https:\/\/www.asimute.uha.fr\/de\/\">Accueil<\/a><\/span><\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2148d81 e-flex e-con-boxed e-con e-parent\" data-id=\"2148d81\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-22936ce elementor-widget elementor-widget-menu-anchor\" data-id=\"22936ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"haut-de-page\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-38c64eb elementor-widget__width-auto elementor-widget elementor-widget-post-info\" data-id=\"38c64eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-inline-items elementor-icon-list-items elementor-post-info\">\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-537b951 elementor-inline-item\" itemprop=\"about\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-terms\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-post-info__terms-list\">\n\t\t\t\t<span class=\"elementor-post-info__terms-list-item\">Interview<\/span>\t\t\t\t<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9fec24c elementor-widget elementor-widget-post-info\" data-id=\"9fec24c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-post-info\">\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-98a5ae7\" itemprop=\"datePublished\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-date\">\n\t\t\t\t\t\t\t<span class=\"elementor-post-info__item-prefix\">Ver\u00f6ffentlicht am<\/span>\n\t\t\t\t\t\t\t\t\t\t<time>11.02.2025<\/time>\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef0fb85 elementor-share-buttons--view-icon elementor-share-buttons--color-custom elementor-share-buttons--skin-minimal elementor-share-buttons--shape-square elementor-grid-0 elementor-widget elementor-widget-share-buttons\" data-id=\"ef0fb85\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"share-buttons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_facebook\" role=\"button\" tabindex=\"0\" aria-label=\"Partager sur facebook\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_x-twitter\" role=\"button\" tabindex=\"0\" aria-label=\"Partager sur x-twitter\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-x-twitter\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M389.2 48h70.6L305.6 224.2 487 464H345L233.7 318.6 106.5 464H35.8L200.7 275.5 26.8 48H172.4L272.9 180.9 389.2 48zM364.4 421.8h39.1L151.1 88h-42L364.4 421.8z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_linkedin\" role=\"button\" tabindex=\"0\" aria-label=\"Partager sur linkedin\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-linkedin\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 32H31.9C14.3 32 0 46.5 0 64.3v383.4C0 465.5 14.3 480 31.9 480H416c17.6 0 32-14.5 32-32.3V64.3c0-17.8-14.4-32.3-32-32.3zM135.4 416H69V202.2h66.5V416zm-33.2-243c-21.3 0-38.5-17.3-38.5-38.5S80.9 96 102.2 96c21.2 0 38.5 17.3 38.5 38.5 0 21.3-17.2 38.5-38.5 38.5zm282.1 243h-66.4V312c0-24.8-.5-56.7-34.5-56.7-34.6 0-39.9 27-39.9 54.9V416h-66.4V202.2h63.7v29.2h.9c8.9-16.8 30.6-34.5 62.9-34.5 67.2 0 79.7 44.3 79.7 101.9V416z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bc127bb elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"bc127bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"750\" height=\"430\" src=\"https:\/\/www.asimute.uha.fr\/de\/wp-content\/uploads\/2025\/02\/asimute-interview-djaffar-ould-energie.webp\" class=\"attachment-large size-large wp-image-1539\" alt=\"\" srcset=\"https:\/\/www.asimute.uha.fr\/de\/wp-content\/uploads\/2025\/02\/asimute-interview-djaffar-ould-energie.webp 750w, https:\/\/www.asimute.uha.fr\/de\/wp-content\/uploads\/2025\/02\/asimute-interview-djaffar-ould-energie-300x172.webp 300w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bd9b611 elementor-widget elementor-widget-text-editor\" data-id=\"bd9b611\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div id=\"lipsum\"><p><em>Das ASIMUTE-Projekt ist ein multidisziplin\u00e4res europ\u00e4isches Forschungsprojekt, das Frauen und M\u00e4nner mit unterschiedlichen Hintergr\u00fcnden zusammenbringt. Ihre Hintergr\u00fcnde sind unterschiedlich, aber alle diese Menschen engagieren sich, um die Forschung voranzutreiben. In einer Reihe von Miniportr\u00e4ts erfahren wir, wer sie sind und was sie motiviert.<\/em><\/p><p><em>F\u00fcr dieses erste Interview hat sich der Koordinator des ASIMUTE-Projekts, Prof. Ould-Abdeslam, bereit erkl\u00e4rt, unsere Fragen zu beantworten.<br \/><\/em><\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a4d93e4 e-con-full e-flex e-con e-child\" data-id=\"a4d93e4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6c34f5a elementor-position-inline-end elementor-mobile-position-inline-start elementor-widget__width-auto elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"6c34f5a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/www.linkedin.com\/in\/djaffar-ould-abdeslam-55589526\/\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Djaffar Ould-Abdeslam\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-linkedin\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 32H31.9C14.3 32 0 46.5 0 64.3v383.4C0 465.5 14.3 480 31.9 480H416c17.6 0 32-14.5 32-32.3V64.3c0-17.8-14.4-32.3-32-32.3zM135.4 416H69V202.2h66.5V416zm-33.2-243c-21.3 0-38.5-17.3-38.5-38.5S80.9 96 102.2 96c21.2 0 38.5 17.3 38.5 38.5 0 21.3-17.2 38.5-38.5 38.5zm282.1 243h-66.4V312c0-24.8-.5-56.7-34.5-56.7-34.6 0-39.9 27-39.9 54.9V416h-66.4V202.2h63.7v29.2h.9c8.9-16.8 30.6-34.5 62.9-34.5 67.2 0 79.7 44.3 79.7 101.9V416z\"><\/path><\/svg>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.linkedin.com\/in\/djaffar-ould-abdeslam-55589526\/\" target=\"_blank\" >\n\t\t\t\t\t\t\tDjaffar Ould-Abdeslam\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5dc914f elementor-position-inline-end elementor-mobile-position-inline-start elementor-widget__width-auto elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"5dc914f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/www.uha.fr\/de\/index.html\" target=\"_blank\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Universit\u00e9 de Haute-Alsace\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-university\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M496 128v16a8 8 0 0 1-8 8h-24v12c0 6.627-5.373 12-12 12H60c-6.627 0-12-5.373-12-12v-12H24a8 8 0 0 1-8-8v-16a8 8 0 0 1 4.941-7.392l232-88a7.996 7.996 0 0 1 6.118 0l232 88A8 8 0 0 1 496 128zm-24 304H40c-13.255 0-24 10.745-24 24v16a8 8 0 0 0 8 8h464a8 8 0 0 0 8-8v-16c0-13.255-10.745-24-24-24zM96 192v192H60c-6.627 0-12 5.373-12 12v20h416v-20c0-6.627-5.373-12-12-12h-36V192h-64v192h-64V192h-64v192h-64V192H96z\"><\/path><\/svg>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.uha.fr\/de\/index.html\" target=\"_blank\" >\n\t\t\t\t\t\t\tUniversit\u00e9 de Haute-Alsace\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f93013a elementor-widget elementor-widget-text-editor\" data-id=\"f93013a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 500;\">Frage 1: Was ist Ihr pers\u00f6nlicher Werdegang und was hat Sie dazu bewogen, eine wissenschaftliche Laufbahn einzuschlagen?<\/span><\/p><div><span style=\"font-weight: 500;\">Projektkoordinator: <\/span>W\u00e4hrend meines technischen Ingenieurstudiums in Tizi Ouzou, Algerien, habe ich ein Forschungspraktikum in einem Labor absolviert. Diese Erfahrung hat mich dazu inspiriert, in den Bereichen Automatisierung, Elektronik und Steuerung zu forschen. Im Anschluss an dieses Praktikum begann ich daher einen Masterstudiengang im Bereich K\u00fcnstliche Intelligenz und Produktionstechnik, der mich mit k\u00fcnstlichen neuronalen Netzen vertraut machte. Danach begann ich in Mulhouse unter der Leitung von Jean Merckl\u00e9 eine Doktorarbeit, deren Thema sich mit k\u00fcnstlicher Intelligenz befasste, die auf elektrische Systeme angewandt wurde. Damals waren wir jedoch \u201ehors sol\u201c, da es in der Gemeinschaft der Automatiker nur wenige gab, die an diesen Themen arbeiteten. Wir mussten unsere Anstrengungen verdoppeln, um zu beweisen, dass unsere Ergebnisse wertvoll waren.<\/div><div>\u00a0<\/div><div id=\"lipsum\" style=\"font-weight: 500;\">Frage 2: Warum haben Sie sich f\u00fcr dieses Forschungsgebiet entschieden?<\/div><div>\u00a0<\/div><div><span style=\"font-weight: 500;\">Projektkoordinator:<\/span> Meine Attraktivit\u00e4t f\u00fcr dieses Fachgebiet wurde w\u00e4hrend meiner Doktorarbeit deutlich, weil ich konkrete L\u00f6sungen finden wollte, die sich wirklich auf die nachhaltige Entwicklung, die Senkung des Energieverbrauchs und die Entwicklung alternativer Produktionsmittel auswirken w\u00fcrden, um den CO2-Fu\u00dfabdruck der menschlichen Aktivit\u00e4ten deutlich zu verringern. Meiner Meinung nach ber\u00fchrt dieser Forschungsbereich den menschlichen Aspekt, die Verbesserung unserer Gesellschaften und das t\u00e4gliche Leben der B\u00fcrger. Jede vorgeschlagene L\u00f6sung hat potenziell unmittelbare Anwendungen und Auswirkungen. Und alles muss noch erfunden werden.<\/div><div>\u00a0<\/div><div id=\"lipsum\" style=\"font-weight: 500;\">Frage 3: Wie ist Ihr Forschungsbereich mit dem Projekt verkn\u00fcpft?<\/div><div>\u00a0<\/div><div><span style=\"font-weight: 500;\">Projektkoordinator: <\/span>Ich habe das Gl\u00fcck, dass meine Lieblingsgebiete (k\u00fcnstliche Intelligenz und Energie) im Zentrum von ASIMUTE stehen. Als Projektkoordinator hatte ich die M\u00f6glichkeit, von diesen Bereichen auszugehen und nach erg\u00e4nzenden Partnern in der Oberrheinregion zu suchen, mit dem Ziel, an einem Projekt zur nachhaltigen Entwicklung zu arbeiten.<\/div><div>\u00a0<\/div><div><span style=\"font-weight: 500;\">Frage 4: Was war die erste Frage, die Sie sich selbst zu Beginn des Projekts gestellt haben?<\/span><\/div><div>\u00a0<\/div><div><p><span style=\"font-weight: 500;\">Projektkoordinator: <\/span>Das ist eine Frage, auf die ich in zwei Schritten antworten werde. Als Projekttr\u00e4ger habe ich mich gefragt, wie man eine Komplementarit\u00e4t zwischen Partnern mit so unterschiedlichen Forschungsgebieten hervorbringen kann. Da ASIMUTE ein multidisziplin\u00e4res Projekt ist, ber\u00fchrt man Themen wie Soziologie, Recht, Technologie, aber auch Cybersicherheit. Und ich wollte diese Disziplinen zusammenbringen und gleichzeitig die Bedeutung jeder einzelnen von ihnen hervorheben.<\/p><p>Und als Wissenschaftler stellte ich mir die Frage nach der Anwendbarkeit des Projekts. Per Definition beinhaltet Forschung eine Unbekannte, aber ich wollte, dass unsere Ergebnisse echte und sehr kurzfristige Auswirkungen auf die Unternehmen, Beh\u00f6rden und Universit\u00e4ten in der Region haben.<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-341c828 elementor-blockquote--skin-quotation elementor-widget__width-initial elementor-widget elementor-widget-blockquote\" data-id=\"341c828\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"blockquote.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<blockquote class=\"elementor-blockquote\">\n\t\t\t<p class=\"elementor-blockquote__content\">\n\t\t\t\tPer Definition beinhaltet Forschung eine Unbekannte, aber ich wollte, dass unsere Ergebnisse echte und sehr kurzfristig\t\t\t<\/p>\n\t\t\t\t\t<\/blockquote>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ed697be elementor-widget elementor-widget-text-editor\" data-id=\"ed697be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div id=\"lipsum\" style=\"font-weight: 500;\">Frage 5: Haben Sie diese Frage bisher beantwortet?<\/div><div>\u00a0<\/div><div><p><span style=\"font-weight: 500;\">Projektkoordinator: <\/span>Mit der Arbeit an unserem vorherigen Projekt &#8211; dem Projekt Smart Meter Inclusive, in dessen Rahmen wir einen intelligenten Z\u00e4hler f\u00fcr Haushalte entwickelt haben, um ihnen zu helfen, ihren Energieverbrauch zu optimieren &#8211; konnten wir Verbrauchsdaten von Z\u00e4hlern sammeln, die in mehreren Versuchsgeb\u00e4uden vorinstalliert waren. Sie erm\u00f6glichten es uns, unsere eigenen Daten zu generieren, deren Umfang mit der Zeit immer gr\u00f6\u00dfer werden wird.<\/p><p>Aus soziologischer Sicht haben wir auch viele Daten aus den laufenden gesellschaftlichen Studien (<a href=\"https:\/\/www.asimute.uha.fr\/de\/2024\/05\/30\/energieeinsparung-und-kompensatorischer-verbrauch\/\" rel=\"noopener\">WP3<\/a> und <a href=\"https:\/\/www.asimute.uha.fr\/de\/2024\/05\/31\/glauben-und-hierarchie-der-erwartungen-von-haushalten-an-technologische-gerate-fur-den-eigenverbrauch-von-energie-welchen-status-hat-die-erwartung-einer-kontinuierlichen-verbesserung\/\" rel=\"noopener\">WP4<\/a>). In der Tat haben wir die Antworten einer Stichprobe von B\u00fcrgern durch soziologische Umfragen gesammelt. Dies gibt uns eine Vorstellung davon, was die Einf\u00fchrung eines intelligenten Ger\u00e4ts in den Haushalten behindern k\u00f6nnte. Diese Informationen sind von entscheidender Bedeutung, da sie es uns erm\u00f6glichen, die Nutzung des Z\u00e4hlers auszugleichen oder zu \u00fcberdenken.<\/p><p>Aus wissenschaftlicher Sicht arbeitet das <a href=\"https:\/\/www.asimute.uha.fr\/de\/2024\/06\/03\/second-life-batterien-fur-den-eigenverbrauch\/\" rel=\"noopener\">Arbeitspaket 10<\/a> an einer L\u00f6sung zur Optimierung des Eigenverbrauchs der Batterien von Elektrofahrzeugen. Diese L\u00f6sung hat die Validierungsschritte der Berichterstatter des \u201eJournal of Energy Storage\u201c, einer hochrangigen wissenschaftlichen Publikationszeitschrift, durchlaufen. Der von Hadi Mawassi, Gilles Hermann, Lhassane Idoumghar und mir eingereichte Artikel ist leicht im Internet zu finden (<a href=\"https:\/\/www.sciencedirect.com\/science\/article\/abs\/pii\/S2352152X24046206\" rel=\"\">link<\/a>).<\/p><\/div><div id=\"lipsum\" style=\"font-weight: 500;\">Frage 6: Was k\u00f6nnen Sie uns \u00fcber Ihre aktuellen Erkenntnisse mitteilen, ohne zu viel preiszugeben?<\/div><div>\u00a0<\/div><div><span style=\"font-weight: 500;\">Projektkoordinator:<\/span> Bisher gibt es f\u00fcr Batterien von Elektroautos keine echte Recyclingl\u00f6sung, die \u00fcber ihre urspr\u00fcngliche Verwendung hinausgeht. Ein Team des IRIMAS-Instituts arbeitet jedoch an diesem Thema, da wir glauben, dass sie wiederverwendet werden k\u00f6nnen. Zun\u00e4chst m\u00fcssen wir eine L\u00f6sung finden, um die Zellen innerhalb der Batterie mithilfe von k\u00fcnstlicher Intelligenz wieder ins Gleichgewicht zu bringen. In dem bereits erw\u00e4hnten Artikel zeigt unsere neue Methode, dass der Gesundheitszustand einer Batterie, ihre Alterung im Laufe der Zeit, mit ihrem Ladezustand korreliert. Mit anderen Worten: Je weiter der Gesundheitszustand einer Batterie fortgeschritten ist, desto ungenauer kann sie den Ladezustand einsch\u00e4tzen. Um die Lebensdauer einer Batterie zu verl\u00e4ngern, ist eine Korrelation zwischen den beiden Zust\u00e4nden notwendig.<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3cf9b2f e-flex e-con-boxed e-con e-parent\" data-id=\"3cf9b2f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;background_motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:28,&quot;end&quot;:74}},&quot;background_motion_fx_devices&quot;:[&quot;widescreen&quot;,&quot;desktop&quot;,&quot;laptop&quot;,&quot;tablet_extra&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7f1e81b elementor-widget elementor-widget-image\" data-id=\"7f1e81b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1500\" height=\"846\" src=\"https:\/\/www.asimute.uha.fr\/de\/wp-content\/uploads\/2025\/02\/projet-ASIMUTE-WP10-coordinateur-Interview.webp\" class=\"attachment-full size-full wp-image-1522\" alt=\"\" srcset=\"https:\/\/www.asimute.uha.fr\/de\/wp-content\/uploads\/2025\/02\/projet-ASIMUTE-WP10-coordinateur-Interview.webp 1500w, https:\/\/www.asimute.uha.fr\/de\/wp-content\/uploads\/2025\/02\/projet-ASIMUTE-WP10-coordinateur-Interview-300x169.webp 300w, https:\/\/www.asimute.uha.fr\/de\/wp-content\/uploads\/2025\/02\/projet-ASIMUTE-WP10-coordinateur-Interview-1024x578.webp 1024w, https:\/\/www.asimute.uha.fr\/de\/wp-content\/uploads\/2025\/02\/projet-ASIMUTE-WP10-coordinateur-Interview-768x433.webp 768w\" sizes=\"(max-width: 1500px) 100vw, 1500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2e2affa e-flex e-con-boxed e-con e-parent\" data-id=\"2e2affa\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3ed766b elementor-widget elementor-widget-text-editor\" data-id=\"3ed766b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div id=\"lipsum\" style=\"font-weight: 500;\">Frage 7: Wann und warum begannen Sie mit der Arbeit an umweltbezogenen Projekten?<\/div><div>\u00a0<\/div><div><p><span style=\"font-weight: 500;\">Projektkoordinator: <\/span>Das geht auf die fr\u00fchen 2000er Jahre zur\u00fcck, als ich meine Doktorarbeit schrieb. Ich arbeitete an der Energiequalit\u00e4t und insbesondere an Stromoberschwingungen, um das Verhalten eines neuronalen Netzes gegen\u00fcber diesen externen \u201eVerschmutzungen\u201c zu untersuchen. Dies bewies, dass diese \u201eVerschmutzungen\u201c die Ger\u00e4te schneller altern lie\u00dfen. Daher beschloss ich, das Thema weiter zu vertiefen und an L\u00f6sungen zur Verringerung dieser Verschmutzungen und zur Optimierung der Energieeffizienz zu arbeiten.<\/p><p>Aus pers\u00f6nlicher Sicht liebe ich es, in die Berge zu fahren, zu wandern und neue Landschaften zu entdecken. Ich wei\u00df, dass ich gro\u00dfes Gl\u00fcck habe, diese nat\u00fcrlichen Orte zu sehen und zu genie\u00dfen. Dieses Gleichgewicht m\u00f6chte ich f\u00fcr k\u00fcnftige Generationen bewahren. Dies ist nur m\u00f6glich, indem wir erschwingliche innovative L\u00f6sungen entwickeln. Andernfalls werden sich die Auswirkungen des Klimawandels beschleunigen und D\u00fcrreperioden, Hungersn\u00f6te, aber auch Vertreibungen von Menschen verst\u00e4rken.<\/p><\/div><div id=\"lipsum\" style=\"font-weight: 500;\">Frage 8: Warum ist die Energieoptimierung auf europ\u00e4ischer Ebene wichtig?<\/div><div>\u00a0<\/div><div><span style=\"font-weight: 500;\">Projektkoordinator:<\/span> Zun\u00e4chst einmal verf\u00fcgt Europa nur \u00fcber wenige \u00d6l- und fossile Energieressourcen. Die Ausbeutung dieser Reserven muss unbedingt vermieden werden, da dies zu einer Beschleunigung der globalen Erw\u00e4rmung f\u00fchren w\u00fcrde. Was erneuerbare Energien wie Solar- und Windenergie betrifft, so h\u00e4ngt ihre Nutzung stark von den Wetterbedingungen ab. Um diese Problematik anzugehen und die Zeiten der Produktion mit denen der Nutzung in Einklang zu bringen, muss Europa die Energie intelligent verwalten. Und genau das ist das Ziel des ASIMUTE-Projekts: die Nutzung der in Europa erzeugten Energie zu optimieren. Dies ist eine Notwendigkeit, wenn man eine dauerhafte Energiereserve schaffen und potenzielle Versorgungsprobleme vermeiden will.<\/div><div>\u00a0<\/div><div id=\"lipsum\" style=\"font-weight: 500;\">Frage 9: Sind Sie begeistert von anderen Projekten, sind es Ihre eigenen oder die von jemand anderem?<\/div><div>\u00a0<\/div><div><span style=\"font-weight: 500;\">Projektkoordinator: <\/span>Es gibt viele davon, aber ich habe keine andere Wahl, als mich auf eine Handvoll zu konzentrieren. Zun\u00e4chst gibt es das Projekt <a href=\"https:\/\/co2inno.com\/de\/\" target=\"_blank\" rel=\"noopener\">CO2Inno<\/a>, das von der Universit\u00e4t Freiburg koordiniert wird und an einem Reallabor \u201eCO2-neutrale Innovationsregion Oberrhein\u201c arbeitet. Da gibt es das Projekt Energetic, das vom <a href=\"https:\/\/www.insa-strasbourg.fr\/fr\/\" target=\"_blank\" rel=\"noopener\">INSA<\/a> (Institut National des Sciences Appliqu\u00e9es) in Stra\u00dfburg entwickelt wurde und sich mit der optimalen Nutzung von Elektrobatterien befasst. Dann gibt es das <a href=\"https:\/\/www.ines-solaire.org\/\" target=\"_blank\" rel=\"noopener\">INES<\/a> (Institut National de l&rsquo;Energie Solaire), das mehrere Projekte zur Optimierung von Sonnenkollektoren und deren Nutzung entwickelt. Und schlie\u00dflich das von Interreg entwickelte Projekt <a href=\"https:\/\/www.interreg-rhin-sup.eu\/projet\/sumo-rhine-sustainable-mobility-rhine-faciliter-la-mobilite-durable-dans-la-region-du-rhin-superieur\/\" target=\"_blank\" rel=\"noopener\">SuMo-Rhine<\/a> (Sustainable Mobility Rhine), das die sanfte Mobilit\u00e4t in der Oberrheinregion erleichtern will. F\u00fcr mich sind dies Projekte, die ASIMUTE erg\u00e4nzen, da sie L\u00f6sungen vorschlagen, die sich auf unsere Gesellschaften und die Umwelt auswirken werden.<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a86f395 e-flex e-con-boxed e-con e-parent\" data-id=\"a86f395\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;background_motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:28,&quot;end&quot;:74}},&quot;background_motion_fx_devices&quot;:[&quot;widescreen&quot;,&quot;desktop&quot;,&quot;laptop&quot;,&quot;tablet_extra&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6de06cf elementor-widget elementor-widget-spacer\" data-id=\"6de06cf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-02f03c1 e-flex e-con-boxed e-con e-parent\" data-id=\"02f03c1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2e2adc4 elementor-widget elementor-widget-text-editor\" data-id=\"2e2adc4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div id=\"lipsum\" style=\"font-weight: 500;\">Frage 10: Wie kam die Idee f\u00fcr dieses Projekt zustande?<\/div><div>\u00a0<\/div><div><span style=\"font-weight: 500;\">Projektkoordinator:<\/span> Am Ende des SMI-Projekts wollten alle Partner auf dieser kollaborativen Dynamik aufbauen und ein weiteres Projekt starten. Wir hatten bereits eine Verbindung zwischen intelligenten Stromz\u00e4hlern und ihrer Verwendung in der Zivilgesellschaft hergestellt und wollten unsere Forschung zum Thema Eigenverbrauch vertiefen. Wir befassten uns also mit verschiedenen Fallbeispielen und fragten uns, welche anderen Bereiche vom Eigenverbrauch betroffen sein k\u00f6nnten. Und als wir unsere \u00dcberlegungen verfeinerten, entschieden wir uns f\u00fcr die Arbeit zum Thema Eigenverbrauch und Energieoptimierung mithilfe eines intelligenten Z\u00e4hlers.<\/div><div>\u00a0<\/div><div id=\"lipsum\" style=\"font-weight: 500;\">Frage 11: Wie haben Sie Ihre akademischen Partner gefunden?<\/div><div>\u00a0<\/div><div><span style=\"font-weight: 500;\">Projektkoordinator: <\/span>Wir hatten bereits ein kleines Startnetzwerk, das auf allen Partnern basierte, die am SMI-Projekt gearbeitet hatten. Einige sind immer noch dabei, aber andere mussten gehen, weil sie andere akademische Verpflichtungen hatten. Da die Forschung sehr zeitaufwendig ist und viel investiert, war es ihnen nicht m\u00f6glich, sich zu vervielf\u00e4ltigen. Ausgehend von diesem urspr\u00fcnglichen bzw. neu zusammengesetzten Kern identifizierten wir unsere neuen Bed\u00fcrfnisse und kontaktierten dann Partner, die in der Lage waren, die fehlenden Bed\u00fcrfnisse zu erf\u00fcllen. Dies war ein offener Prozess, in dem wir auch Vorschl\u00e4ge akzeptierten. Interreg war sich dessen bewusst und schlug uns einen neuen Partner vor, der perfekt zu unserer Suche passte. Und wir bereuen es nicht.<\/div><div>\u00a0<\/div><div id=\"lipsum\" style=\"font-weight: 500;\">Frage 12: ADie Europ\u00e4ische Kommission beiseite, war es schwierig, zus\u00e4tzliche Investitionen f\u00fcr dieses Projekt zu gewinnen?<\/div><div>\u00a0<\/div><div><p><span style=\"font-weight: 500;\">Projektkoordinator:\u00a0<\/span>Der Gro\u00dfteil der Finanzierung des ASIMUTE-Projekts stammt von der Europ\u00e4ischen Union \u00fcber das Interreg-Programm, aber auch von der Schweizerischen Eidgenossenschaft und vier ihrer Grenzkantone (Basel-Stadt, Basel-Land, Jura und Aargau). Dar\u00fcber hinaus haben sich die akademischen Partner von Anfang an verpflichtet, einen Teil des Projekts zu finanzieren und ihre Plattformen und Labore zur Verf\u00fcgung zu stellen. Dies bleibt eine Investition. Auch wenn sie nicht finanzieller Art ist, ist es wichtig, sie zu betonen.<\/p><p>Eine weitere, indirekte Finanzierung kommt von den assoziierten Partnern. Es gibt keinen finanziellen Aspekt, aber sie engagieren sich auf andere Weise. Sie k\u00f6nnen z. B. eine Einrichtung zur Verf\u00fcgung stellen, Beratung, Beteiligung oder Interventionen anbieten.<\/p><p>Wie du sehen kannst, k\u00f6nnen sich die Projektmitglieder \u00fcber diese verschiedenen Investitionsquellen freuen.<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9a47453 e-flex e-con-boxed e-con e-parent\" data-id=\"9a47453\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-49727e1 elementor-widget elementor-widget-heading\" data-id=\"49727e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Unsere neuesten Artikel<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-04c6aa1 elementor-grid-4 elementor-grid-tablet_extra-3 elementor-widget-mobile__width-initial elementor-grid-tablet-2 elementor-grid-mobile-1 elementor-widget elementor-widget-loop-grid\" data-id=\"04c6aa1\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;template_id&quot;:&quot;254&quot;,&quot;columns&quot;:4,&quot;columns_tablet_extra&quot;:3,&quot;_skin&quot;:&quot;post&quot;,&quot;columns_tablet&quot;:&quot;2&quot;,&quot;columns_mobile&quot;:&quot;1&quot;,&quot;edit_handle_selector&quot;:&quot;[data-elementor-type=\\&quot;loop-item\\&quot;]&quot;,&quot;row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_widescreen&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_laptop&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_tablet_extra&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"loop-grid.post\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-loop-container elementor-grid\" role=\"list\">\n\t\t<style id=\"loop-254\">.elementor-254 .elementor-element.elementor-element-4a4c1a5{--display:flex;--flex-direction:column;--container-widget-width:100%;--container-widget-height:initial;--container-widget-flex-grow:0;--container-widget-align-self:initial;--flex-wrap-mobile:wrap;--gap:0px 0px;--row-gap:0px;--column-gap:0px;box-shadow:3px 3px 10px 1px rgba(0, 0, 0, 0.08);--padding-top:0px;--padding-bottom:0px;--padding-left:0px;--padding-right:0px;}.elementor-254 .elementor-element.elementor-element-4a4c1a5:not(.elementor-motion-effects-element-type-background), .elementor-254 .elementor-element.elementor-element-4a4c1a5 > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-color:#FFFFFF;}.elementor-254 .elementor-element.elementor-element-4a4c1a5:hover{box-shadow:3px 3px 10px 1px rgba(0, 0, 0, 0.15);}.elementor-254 .elementor-element.elementor-element-2b1f6df{text-align:center;}.elementor-254 .elementor-element.elementor-element-2b1f6df img{width:100%;height:170px;object-fit:cover;object-position:center center;transition-duration:0.3s;}.elementor-254 .elementor-element.elementor-element-2b1f6df > .elementor-widget-container{margin:0px 0px 0px 0px;padding:0px 0px 0px 0px;}.elementor-254 .elementor-element.elementor-element-0eb427a{--display:flex;--flex-direction:column;--container-widget-width:100%;--container-widget-height:initial;--container-widget-flex-grow:0;--container-widget-align-self:initial;--flex-wrap-mobile:wrap;--justify-content:space-between;--gap:020px 20px;--row-gap:020px;--column-gap:20px;--padding-top:20px;--padding-bottom:15px;--padding-left:20px;--padding-right:20px;}.elementor-254 .elementor-element.elementor-element-e3dc3cd{--display:flex;--min-height:162px;--justify-content:flex-start;--padding-top:0px;--padding-bottom:0px;--padding-left:0px;--padding-right:0px;}.elementor-254 .elementor-element.elementor-element-e3dc3cd.e-con{--align-self:flex-start;}.elementor-254 .elementor-element.elementor-element-e4350c8 .elementor-icon-list-icon{width:14px;}.elementor-254 .elementor-element.elementor-element-e4350c8 .elementor-icon-list-icon i{font-size:14px;}.elementor-254 .elementor-element.elementor-element-e4350c8 .elementor-icon-list-icon svg{--e-icon-list-icon-size:14px;}.elementor-254 .elementor-element.elementor-element-fbd4fc1 .elementor-heading-title a:hover, .elementor-254 .elementor-element.elementor-element-fbd4fc1 .elementor-heading-title a:focus{color:var( --e-global-color-ade3a01 );}.elementor-254 .elementor-element.elementor-element-fbd4fc1 .elementor-heading-title a{transition-duration:0.3s;}.elementor-254 .elementor-element.elementor-element-d6d9539 .elementor-widget-container{font-family:\"Roboto\", Sans-serif;font-size:1em;font-weight:300;line-height:1.5em;}.elementor-254 .elementor-element.elementor-element-d6d9539 > .elementor-widget-container{margin:0px 0px -10px 0px;}.elementor-254 .elementor-element.elementor-element-9791f49{--display:flex;--justify-content:flex-end;--padding-top:0px;--padding-bottom:0px;--padding-left:0px;--padding-right:0px;}.elementor-254 .elementor-element.elementor-element-034b267 .elementor-button{font-size:1.1em;fill:var( --e-global-color-text );color:var( --e-global-color-text );background-color:#66161600;padding:0px 0px 0px 0px;}.elementor-254 .elementor-element.elementor-element-034b267 .elementor-button:hover, .elementor-254 .elementor-element.elementor-element-034b267 .elementor-button:focus{color:var( --e-global-color-06030b6 );}.elementor-254 .elementor-element.elementor-element-034b267 .elementor-button:hover svg, .elementor-254 .elementor-element.elementor-element-034b267 .elementor-button:focus svg{fill:var( --e-global-color-06030b6 );}.elementor-254 .elementor-element.elementor-element-034b267 > .elementor-widget-container{margin:0px 0px 0px 0px;}.elementor-254 .elementor-element.elementor-element-33629af .elementor-icon-list-icon{width:14px;}.elementor-254 .elementor-element.elementor-element-33629af .elementor-icon-list-icon i{font-size:14px;}.elementor-254 .elementor-element.elementor-element-33629af .elementor-icon-list-icon svg{--e-icon-list-icon-size:14px;}.elementor-254 .elementor-element.elementor-element-33ad49d{--display:flex;--padding-top:20px;--padding-bottom:15px;--padding-left:20px;--padding-right:20px;}.elementor-254 .elementor-element.elementor-element-12f9f5b .elementor-icon-list-icon{width:14px;}.elementor-254 .elementor-element.elementor-element-12f9f5b .elementor-icon-list-icon i{font-size:14px;}.elementor-254 .elementor-element.elementor-element-12f9f5b .elementor-icon-list-icon svg{--e-icon-list-icon-size:14px;}.elementor-254 .elementor-element.elementor-element-6472f5c .elementor-widget-container{font-family:\"Roboto\", Sans-serif;font-size:1em;font-weight:300;line-height:1.5em;}.elementor-254 .elementor-element.elementor-element-6472f5c > .elementor-widget-container{margin:0px 0px -10px 0px;}.elementor-254 .elementor-element.elementor-element-6993dec .elementor-button{font-size:1.1em;fill:var( --e-global-color-text );color:var( --e-global-color-text );background-color:#66161600;padding:0px 0px 0px 0px;}.elementor-254 .elementor-element.elementor-element-6993dec .elementor-button:hover, .elementor-254 .elementor-element.elementor-element-6993dec .elementor-button:focus{color:var( --e-global-color-06030b6 );}.elementor-254 .elementor-element.elementor-element-6993dec .elementor-button:hover svg, .elementor-254 .elementor-element.elementor-element-6993dec .elementor-button:focus svg{fill:var( --e-global-color-06030b6 );}.elementor-254 .elementor-element.elementor-element-6993dec > .elementor-widget-container{margin:0px 0px 20px 0px;}.elementor-254 .elementor-element.elementor-element-e547f56 .elementor-icon-list-icon{width:14px;}.elementor-254 .elementor-element.elementor-element-e547f56 .elementor-icon-list-icon i{font-size:14px;}.elementor-254 .elementor-element.elementor-element-e547f56 .elementor-icon-list-icon svg{--e-icon-list-icon-size:14px;}@media(min-width:768px){.elementor-254 .elementor-element.elementor-element-4a4c1a5{--content-width:100%;}.elementor-254 .elementor-element.elementor-element-0eb427a{--content-width:100%;}}@media(max-width:1366px){.elementor-254 .elementor-element.elementor-element-2b1f6df img{object-position:center center;}.elementor-254 .elementor-element.elementor-element-2b1f6df > .elementor-widget-container{margin:0px 0px 0px 0px;}}@media(max-width:1200px){.elementor-254 .elementor-element.elementor-element-e3dc3cd{--min-height:120px;}}@media(max-width:1024px){.elementor-254 .elementor-element.elementor-element-2b1f6df img{height:100%;}}\/* Start custom CSS for container, class: .elementor-element-4a4c1a5 *\/\/*------ ELEMENT \"CATEGORIE\" ------*\/\n.elementor-254 .elementor-element.elementor-element-4a4c1a5 .elementor-post-info__terms-list-item{\n\/*----- FORMER BLUE -----\nbackground-color: #227CB4 *\/\nbackground-color: #56AADF;;\npadding : 3px 10px;\nfont-family: Roboto;\nfont-size: 0.7em;\nfont-weight: 500;\ntext-transform: uppercase;\ncolor: #fff;\n}\n\n\/*------ ELEMENT \"DATE\" ------*\/\n.elementor-254 .elementor-element.elementor-element-4a4c1a5 .elementor-post-info__item--type-date{\nfont-size: .85em;\nfont-weight: 400;\n}\n\n\/*------ CHGT OPACITE IMAGE - SURVOL ------*\/\n.elementor-254 .elementor-element.elementor-element-4a4c1a5 .displayed-image{\ntransition: opacity .4s ease;\n}\n.elementor-254 .elementor-element.elementor-element-4a4c1a5 .e-con-inner:hover .displayed-image{\nopacity: .8;\n}\/* End custom CSS *\/<\/style>\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"254\" class=\"elementor elementor-254 e-loop-item e-loop-item-2200 post-2200 post type-post status-publish format-standard has-post-thumbnail hentry category-artikel\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1270\" class=\"elementor-element elementor-element-4a4c1a5 e-flex e-con-boxed e-con e-parent\" data-id=\"4a4c1a5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2b1f6df displayed-image elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"2b1f6df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.asimute.uha.fr\/de\/2026\/06\/22\/teilnahme-messe-ici-on-agit-strasburg-asimute\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.asimute.uha.fr\/de\/wp-content\/uploads\/elementor\/thumbs\/IUTSalonStras1-rpig8j70tp8c6eamb2xoxexwrb5ridfwcbet4e5ikw.jpg\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1270\" class=\"elementor-element elementor-element-0eb427a e-flex e-con-boxed e-con e-child\" data-id=\"0eb427a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1270\" class=\"elementor-element elementor-element-e3dc3cd e-con-full e-flex e-con e-child\" data-id=\"e3dc3cd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e4350c8 elementor-widget elementor-widget-post-info\" data-id=\"e4350c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-post-info\">\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-0110e7c\" itemprop=\"about\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-terms\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-post-info__terms-list\">\n\t\t\t\t<span class=\"elementor-post-info__terms-list-item\">Artikel<\/span>\t\t\t\t<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fbd4fc1 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"fbd4fc1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.asimute.uha.fr\/de\/2026\/06\/22\/teilnahme-messe-ici-on-agit-strasburg-asimute\/\">Teilnahme an der Messe \u00ab\u00a0Ici On agit!\u00a0\u00bb in Stra\u00dfburg<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d6d9539 elementor-widget elementor-widget-theme-post-excerpt\" data-id=\"d6d9539\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-excerpt.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p>Am 17. und 18. Juni nahm das Team des Projekts ...\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1270\" class=\"elementor-element elementor-element-9791f49 e-con-full e-flex e-con e-child\" data-id=\"9791f49\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-034b267 elementor-widget elementor-widget-button\" data-id=\"034b267\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.asimute.uha.fr\/de\/2026\/06\/22\/teilnahme-messe-ici-on-agit-strasburg-asimute\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Mehr<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-33629af elementor-widget elementor-widget-post-info\" data-id=\"33629af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-post-info\">\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-0110e7c\" itemprop=\"datePublished\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-date\">\n\t\t\t\t\t\t\t<span class=\"elementor-post-info__item-prefix\">Ver\u00f6ffentlicht am<\/span>\n\t\t\t\t\t\t\t\t\t\t<time>22. Juin 2026<\/time>\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1270\" class=\"elementor-element elementor-element-33ad49d e-con-full elementor-hidden-widescreen elementor-hidden-desktop elementor-hidden-laptop elementor-hidden-tablet_extra elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-child\" data-id=\"33ad49d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-12f9f5b elementor-widget elementor-widget-post-info\" data-id=\"12f9f5b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-post-info\">\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-0110e7c\" itemprop=\"about\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-terms\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-post-info__terms-list\">\n\t\t\t\t<span class=\"elementor-post-info__terms-list-item\">Artikel<\/span>\t\t\t\t<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba7eea7 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"ba7eea7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Teilnahme an der Messe \u00ab\u00a0Ici On agit!\u00a0\u00bb in Stra\u00dfburg<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6472f5c elementor-widget elementor-widget-theme-post-excerpt\" data-id=\"6472f5c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-excerpt.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p>Am 17. und 18. Juni nahm das Team des Projekts ...\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6993dec elementor-widget elementor-widget-button\" data-id=\"6993dec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.asimute.uha.fr\/de\/2026\/06\/22\/teilnahme-messe-ici-on-agit-strasburg-asimute\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Mehr<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e547f56 elementor-widget elementor-widget-post-info\" data-id=\"e547f56\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-post-info\">\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-0110e7c\" itemprop=\"datePublished\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-date\">\n\t\t\t\t\t\t\t<span class=\"elementor-post-info__item-prefix\">Ver\u00f6ffentlicht am<\/span>\n\t\t\t\t\t\t\t\t\t\t<time>22. Juin 2026<\/time>\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"254\" class=\"elementor elementor-254 e-loop-item e-loop-item-2165 post-2165 post type-post status-publish format-standard has-post-thumbnail hentry category-artikel\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1270\" class=\"elementor-element elementor-element-4a4c1a5 e-flex e-con-boxed e-con e-parent\" data-id=\"4a4c1a5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2b1f6df displayed-image elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"2b1f6df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.asimute.uha.fr\/de\/2026\/06\/09\/opal-rt-workshop-2026\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.asimute.uha.fr\/de\/wp-content\/uploads\/elementor\/thumbs\/Opal26-00-rop69cm7advhvuvuufjyiqtl4qa0kemwmzypsmvzgw.webp\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1270\" class=\"elementor-element elementor-element-0eb427a e-flex e-con-boxed e-con e-child\" data-id=\"0eb427a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1270\" class=\"elementor-element elementor-element-e3dc3cd e-con-full e-flex e-con e-child\" data-id=\"e3dc3cd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e4350c8 elementor-widget elementor-widget-post-info\" data-id=\"e4350c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-post-info\">\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-0110e7c\" itemprop=\"about\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-terms\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-post-info__terms-list\">\n\t\t\t\t<span class=\"elementor-post-info__terms-list-item\">Artikel<\/span>\t\t\t\t<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fbd4fc1 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"fbd4fc1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.asimute.uha.fr\/de\/2026\/06\/09\/opal-rt-workshop-2026\/\">Workshop Opal-RT (2026)<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d6d9539 elementor-widget elementor-widget-theme-post-excerpt\" data-id=\"d6d9539\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-excerpt.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p>Am 4. Juni 2026 hatte das ASIMUTE-Projektteam die Freude, Opal-RT, ...\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1270\" class=\"elementor-element elementor-element-9791f49 e-con-full e-flex e-con e-child\" data-id=\"9791f49\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-034b267 elementor-widget elementor-widget-button\" data-id=\"034b267\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.asimute.uha.fr\/de\/2026\/06\/09\/opal-rt-workshop-2026\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Mehr<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-33629af elementor-widget elementor-widget-post-info\" data-id=\"33629af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-post-info\">\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-0110e7c\" itemprop=\"datePublished\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-date\">\n\t\t\t\t\t\t\t<span class=\"elementor-post-info__item-prefix\">Ver\u00f6ffentlicht am<\/span>\n\t\t\t\t\t\t\t\t\t\t<time>9. Juin 2026<\/time>\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1270\" class=\"elementor-element elementor-element-33ad49d e-con-full elementor-hidden-widescreen elementor-hidden-desktop elementor-hidden-laptop elementor-hidden-tablet_extra elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-child\" data-id=\"33ad49d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-12f9f5b elementor-widget elementor-widget-post-info\" data-id=\"12f9f5b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-post-info\">\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-0110e7c\" itemprop=\"about\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-terms\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-post-info__terms-list\">\n\t\t\t\t<span class=\"elementor-post-info__terms-list-item\">Artikel<\/span>\t\t\t\t<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba7eea7 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"ba7eea7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Workshop Opal-RT (2026)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6472f5c elementor-widget elementor-widget-theme-post-excerpt\" data-id=\"6472f5c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-excerpt.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p>Am 4. Juni 2026 hatte das ASIMUTE-Projektteam die Freude, Opal-RT, ...\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6993dec elementor-widget elementor-widget-button\" data-id=\"6993dec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.asimute.uha.fr\/de\/2026\/06\/09\/opal-rt-workshop-2026\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Mehr<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e547f56 elementor-widget elementor-widget-post-info\" data-id=\"e547f56\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-post-info\">\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-0110e7c\" itemprop=\"datePublished\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-date\">\n\t\t\t\t\t\t\t<span class=\"elementor-post-info__item-prefix\">Ver\u00f6ffentlicht am<\/span>\n\t\t\t\t\t\t\t\t\t\t<time>9. Juin 2026<\/time>\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"254\" class=\"elementor elementor-254 e-loop-item e-loop-item-2127 post-2127 post type-post status-publish format-standard has-post-thumbnail hentry category-artikel\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1270\" class=\"elementor-element elementor-element-4a4c1a5 e-flex e-con-boxed e-con e-parent\" data-id=\"4a4c1a5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2b1f6df displayed-image elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"2b1f6df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.asimute.uha.fr\/de\/2026\/03\/24\/asimute-kolloquium-drei-jahres\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.asimute.uha.fr\/de\/wp-content\/uploads\/elementor\/thumbs\/March20-Asimute-workshop-01-rkze7w9m8r7l35b6ekng3fwfpnoj5p5t49wzrhd8wg.png\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1270\" class=\"elementor-element elementor-element-0eb427a e-flex e-con-boxed e-con e-child\" data-id=\"0eb427a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1270\" class=\"elementor-element elementor-element-e3dc3cd e-con-full e-flex e-con e-child\" data-id=\"e3dc3cd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e4350c8 elementor-widget elementor-widget-post-info\" data-id=\"e4350c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-post-info\">\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-0110e7c\" itemprop=\"about\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-terms\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-post-info__terms-list\">\n\t\t\t\t<span class=\"elementor-post-info__terms-list-item\">Artikel<\/span>\t\t\t\t<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fbd4fc1 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"fbd4fc1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.asimute.uha.fr\/de\/2026\/03\/24\/asimute-kolloquium-drei-jahres\/\">ASIMUTE-Kolloquium des 3. Jahres<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d6d9539 elementor-widget elementor-widget-theme-post-excerpt\" data-id=\"d6d9539\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-excerpt.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p>Das 3. Nachfolgekolloquium des Projekts ASIMUTE fand am Freitag, den ...\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1270\" class=\"elementor-element elementor-element-9791f49 e-con-full e-flex e-con e-child\" data-id=\"9791f49\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-034b267 elementor-widget elementor-widget-button\" data-id=\"034b267\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.asimute.uha.fr\/de\/2026\/03\/24\/asimute-kolloquium-drei-jahres\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Mehr<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-33629af elementor-widget elementor-widget-post-info\" data-id=\"33629af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-post-info\">\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-0110e7c\" itemprop=\"datePublished\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-date\">\n\t\t\t\t\t\t\t<span class=\"elementor-post-info__item-prefix\">Ver\u00f6ffentlicht am<\/span>\n\t\t\t\t\t\t\t\t\t\t<time>24. Mar 2026<\/time>\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1270\" class=\"elementor-element elementor-element-33ad49d e-con-full elementor-hidden-widescreen elementor-hidden-desktop elementor-hidden-laptop elementor-hidden-tablet_extra elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-child\" data-id=\"33ad49d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-12f9f5b elementor-widget elementor-widget-post-info\" data-id=\"12f9f5b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-post-info\">\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-0110e7c\" itemprop=\"about\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-terms\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-post-info__terms-list\">\n\t\t\t\t<span class=\"elementor-post-info__terms-list-item\">Artikel<\/span>\t\t\t\t<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba7eea7 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"ba7eea7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">ASIMUTE-Kolloquium des 3. Jahres<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6472f5c elementor-widget elementor-widget-theme-post-excerpt\" data-id=\"6472f5c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-excerpt.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p>Das 3. Nachfolgekolloquium des Projekts ASIMUTE fand am Freitag, den ...\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6993dec elementor-widget elementor-widget-button\" data-id=\"6993dec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.asimute.uha.fr\/de\/2026\/03\/24\/asimute-kolloquium-drei-jahres\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Mehr<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e547f56 elementor-widget elementor-widget-post-info\" data-id=\"e547f56\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-post-info\">\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-0110e7c\" itemprop=\"datePublished\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-date\">\n\t\t\t\t\t\t\t<span class=\"elementor-post-info__item-prefix\">Ver\u00f6ffentlicht am<\/span>\n\t\t\t\t\t\t\t\t\t\t<time>24. Mar 2026<\/time>\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div data-elementor-type=\"loop-item\" data-elementor-id=\"254\" class=\"elementor elementor-254 e-loop-item e-loop-item-2092 post-2092 post type-post status-publish format-standard has-post-thumbnail hentry category-interview\" data-elementor-post-type=\"elementor_library\" data-custom-edit-handle=\"1\">\n\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1270\" class=\"elementor-element elementor-element-4a4c1a5 e-flex e-con-boxed e-con e-parent\" data-id=\"4a4c1a5\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2b1f6df displayed-image elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"2b1f6df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.asimute.uha.fr\/de\/2026\/02\/17\/interview-benedicte-laroze-wissenschaftliche-mitarbeiterin-wp6\/\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.asimute.uha.fr\/de\/wp-content\/uploads\/elementor\/thumbs\/WP6-Laroze-news-pic-rixzjq2ajaynxtwptxtxb81ivzrjzy5grxwga6pvtm.webp\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1270\" class=\"elementor-element elementor-element-0eb427a e-flex e-con-boxed e-con e-child\" data-id=\"0eb427a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1270\" class=\"elementor-element elementor-element-e3dc3cd e-con-full e-flex e-con e-child\" data-id=\"e3dc3cd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e4350c8 elementor-widget elementor-widget-post-info\" data-id=\"e4350c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-post-info\">\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-0110e7c\" itemprop=\"about\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-terms\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-post-info__terms-list\">\n\t\t\t\t<span class=\"elementor-post-info__terms-list-item\">Interview<\/span>\t\t\t\t<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fbd4fc1 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"fbd4fc1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.asimute.uha.fr\/de\/2026\/02\/17\/interview-benedicte-laroze-wissenschaftliche-mitarbeiterin-wp6\/\">Interview mit B\u00e9n\u00e9dicte Laroze LL.M. \u2013 Wissenschaftliche Mitarbeiterin von WP6<\/a><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d6d9539 elementor-widget elementor-widget-theme-post-excerpt\" data-id=\"d6d9539\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-excerpt.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p>Das ASIMUTE-Projekt ist ein multidisziplin\u00e4res europ\u00e4isches Forschungsprojekt, das Frauen und ...\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1270\" class=\"elementor-element elementor-element-9791f49 e-con-full e-flex e-con e-child\" data-id=\"9791f49\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-034b267 elementor-widget elementor-widget-button\" data-id=\"034b267\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.asimute.uha.fr\/de\/2026\/02\/17\/interview-benedicte-laroze-wissenschaftliche-mitarbeiterin-wp6\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Mehr<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-33629af elementor-widget elementor-widget-post-info\" data-id=\"33629af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-post-info\">\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-0110e7c\" itemprop=\"datePublished\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-date\">\n\t\t\t\t\t\t\t<span class=\"elementor-post-info__item-prefix\">Ver\u00f6ffentlicht am<\/span>\n\t\t\t\t\t\t\t\t\t\t<time>17. F\u00e9v 2026<\/time>\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1270\" class=\"elementor-element elementor-element-33ad49d e-con-full elementor-hidden-widescreen elementor-hidden-desktop elementor-hidden-laptop elementor-hidden-tablet_extra elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-child\" data-id=\"33ad49d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-12f9f5b elementor-widget elementor-widget-post-info\" data-id=\"12f9f5b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-post-info\">\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-0110e7c\" itemprop=\"about\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-terms\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-post-info__terms-list\">\n\t\t\t\t<span class=\"elementor-post-info__terms-list-item\">Interview<\/span>\t\t\t\t<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba7eea7 elementor-widget elementor-widget-theme-post-title elementor-page-title elementor-widget-heading\" data-id=\"ba7eea7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Interview mit B\u00e9n\u00e9dicte Laroze LL.M. \u2013 Wissenschaftliche Mitarbeiterin von WP6<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6472f5c elementor-widget elementor-widget-theme-post-excerpt\" data-id=\"6472f5c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-excerpt.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p>Das ASIMUTE-Projekt ist ein multidisziplin\u00e4res europ\u00e4isches Forschungsprojekt, das Frauen und ...\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6993dec elementor-widget elementor-widget-button\" data-id=\"6993dec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.asimute.uha.fr\/de\/2026\/02\/17\/interview-benedicte-laroze-wissenschaftliche-mitarbeiterin-wp6\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Mehr<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e547f56 elementor-widget elementor-widget-post-info\" data-id=\"e547f56\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-post-info\">\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-0110e7c\" itemprop=\"datePublished\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-date\">\n\t\t\t\t\t\t\t<span class=\"elementor-post-info__item-prefix\">Ver\u00f6ffentlicht am<\/span>\n\t\t\t\t\t\t\t\t\t\t<time>17. F\u00e9v 2026<\/time>\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Erfahren Sie mehr \u00fcber Prof. Ould-Abdeslam Werdegang und seine aktuellen Arbeiten in diesem ersten Interview<\/p>\n","protected":false},"author":3,"featured_media":1539,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-1519","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interview"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Interview mit Prof. Ould-Abdeslam - Koordinator des ASIMUTE-Projekts - ASIMUTE - Universit\u00e9 de Haute-Alsace<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asimute.uha.fr\/de\/2025\/02\/11\/interview-prof-ould-abdeslam-koordinator-projekts\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Interview mit Prof. Ould-Abdeslam - Koordinator des ASIMUTE-Projekts - ASIMUTE - Universit\u00e9 de Haute-Alsace\" \/>\n<meta property=\"og:description\" content=\"Erfahren Sie mehr \u00fcber Prof. Ould-Abdeslam Werdegang und seine aktuellen Arbeiten in diesem ersten Interview\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asimute.uha.fr\/de\/2025\/02\/11\/interview-prof-ould-abdeslam-koordinator-projekts\/\" \/>\n<meta property=\"og:site_name\" content=\"ASIMUTE - Universit\u00e9 de Haute-Alsace\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-11T08:24:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-17T08:37:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asimute.uha.fr\/de\/wp-content\/uploads\/2025\/02\/asimute-interview-djaffar-ould-energie.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"430\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"J.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"J.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/2025\\\/02\\\/11\\\/interview-prof-ould-abdeslam-koordinator-projekts\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/2025\\\/02\\\/11\\\/interview-prof-ould-abdeslam-koordinator-projekts\\\/\"},\"author\":{\"name\":\"J.\",\"@id\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/#\\\/schema\\\/person\\\/b03aa6996efd8db50669100bf05ba2a1\"},\"headline\":\"Interview mit Prof. Ould-Abdeslam &#8211; Koordinator des ASIMUTE-Projekts\",\"datePublished\":\"2025-02-11T08:24:14+00:00\",\"dateModified\":\"2025-03-17T08:37:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/2025\\\/02\\\/11\\\/interview-prof-ould-abdeslam-koordinator-projekts\\\/\"},\"wordCount\":1673,\"publisher\":{\"@id\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/2025\\\/02\\\/11\\\/interview-prof-ould-abdeslam-koordinator-projekts\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/asimute-interview-djaffar-ould-energie.webp\",\"articleSection\":[\"Interview\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/2025\\\/02\\\/11\\\/interview-prof-ould-abdeslam-koordinator-projekts\\\/\",\"url\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/2025\\\/02\\\/11\\\/interview-prof-ould-abdeslam-koordinator-projekts\\\/\",\"name\":\"Interview mit Prof. Ould-Abdeslam - Koordinator des ASIMUTE-Projekts - ASIMUTE - Universit\u00e9 de Haute-Alsace\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/2025\\\/02\\\/11\\\/interview-prof-ould-abdeslam-koordinator-projekts\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/2025\\\/02\\\/11\\\/interview-prof-ould-abdeslam-koordinator-projekts\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/asimute-interview-djaffar-ould-energie.webp\",\"datePublished\":\"2025-02-11T08:24:14+00:00\",\"dateModified\":\"2025-03-17T08:37:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/2025\\\/02\\\/11\\\/interview-prof-ould-abdeslam-koordinator-projekts\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/2025\\\/02\\\/11\\\/interview-prof-ould-abdeslam-koordinator-projekts\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/2025\\\/02\\\/11\\\/interview-prof-ould-abdeslam-koordinator-projekts\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/asimute-interview-djaffar-ould-energie.webp\",\"contentUrl\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/asimute-interview-djaffar-ould-energie.webp\",\"width\":750,\"height\":430},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/2025\\\/02\\\/11\\\/interview-prof-ould-abdeslam-koordinator-projekts\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Interview mit Prof. Ould-Abdeslam &#8211; Koordinator des ASIMUTE-Projekts\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/\",\"name\":\"ASIMUTE - Universit\u00e9 de Haute-Alsace\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/#organization\",\"name\":\"ASIMUTE - Universit\u00e9 de Haute-Alsace\",\"url\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Asimute-logo-site2.png\",\"contentUrl\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Asimute-logo-site2.png\",\"width\":313,\"height\":100,\"caption\":\"ASIMUTE - Universit\u00e9 de Haute-Alsace\"},\"image\":{\"@id\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/#\\\/schema\\\/person\\\/b03aa6996efd8db50669100bf05ba2a1\",\"name\":\"J.\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9747a37e258302eedadb3a6cf028e96dd42bb3c11dc640aae55e16b9fb5d4d04?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9747a37e258302eedadb3a6cf028e96dd42bb3c11dc640aae55e16b9fb5d4d04?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9747a37e258302eedadb3a6cf028e96dd42bb3c11dc640aae55e16b9fb5d4d04?s=96&d=mm&r=g\",\"caption\":\"J.\"},\"url\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/author\\\/jerrold-robertuha-fr\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Interview mit Prof. Ould-Abdeslam - Koordinator des ASIMUTE-Projekts - ASIMUTE - Universit\u00e9 de Haute-Alsace","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asimute.uha.fr\/de\/2025\/02\/11\/interview-prof-ould-abdeslam-koordinator-projekts\/","og_locale":"fr_FR","og_type":"article","og_title":"Interview mit Prof. Ould-Abdeslam - Koordinator des ASIMUTE-Projekts - ASIMUTE - Universit\u00e9 de Haute-Alsace","og_description":"Erfahren Sie mehr \u00fcber Prof. Ould-Abdeslam Werdegang und seine aktuellen Arbeiten in diesem ersten Interview","og_url":"https:\/\/www.asimute.uha.fr\/de\/2025\/02\/11\/interview-prof-ould-abdeslam-koordinator-projekts\/","og_site_name":"ASIMUTE - Universit\u00e9 de Haute-Alsace","article_published_time":"2025-02-11T08:24:14+00:00","article_modified_time":"2025-03-17T08:37:20+00:00","og_image":[{"width":750,"height":430,"url":"https:\/\/www.asimute.uha.fr\/de\/wp-content\/uploads\/2025\/02\/asimute-interview-djaffar-ould-energie.webp","type":"image\/webp"}],"author":"J.","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"J.","Dur\u00e9e de lecture estim\u00e9e":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.asimute.uha.fr\/de\/2025\/02\/11\/interview-prof-ould-abdeslam-koordinator-projekts\/#article","isPartOf":{"@id":"https:\/\/www.asimute.uha.fr\/de\/2025\/02\/11\/interview-prof-ould-abdeslam-koordinator-projekts\/"},"author":{"name":"J.","@id":"https:\/\/www.asimute.uha.fr\/de\/#\/schema\/person\/b03aa6996efd8db50669100bf05ba2a1"},"headline":"Interview mit Prof. Ould-Abdeslam &#8211; Koordinator des ASIMUTE-Projekts","datePublished":"2025-02-11T08:24:14+00:00","dateModified":"2025-03-17T08:37:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.asimute.uha.fr\/de\/2025\/02\/11\/interview-prof-ould-abdeslam-koordinator-projekts\/"},"wordCount":1673,"publisher":{"@id":"https:\/\/www.asimute.uha.fr\/de\/#organization"},"image":{"@id":"https:\/\/www.asimute.uha.fr\/de\/2025\/02\/11\/interview-prof-ould-abdeslam-koordinator-projekts\/#primaryimage"},"thumbnailUrl":"https:\/\/www.asimute.uha.fr\/de\/wp-content\/uploads\/2025\/02\/asimute-interview-djaffar-ould-energie.webp","articleSection":["Interview"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.asimute.uha.fr\/de\/2025\/02\/11\/interview-prof-ould-abdeslam-koordinator-projekts\/","url":"https:\/\/www.asimute.uha.fr\/de\/2025\/02\/11\/interview-prof-ould-abdeslam-koordinator-projekts\/","name":"Interview mit Prof. Ould-Abdeslam - Koordinator des ASIMUTE-Projekts - ASIMUTE - Universit\u00e9 de Haute-Alsace","isPartOf":{"@id":"https:\/\/www.asimute.uha.fr\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asimute.uha.fr\/de\/2025\/02\/11\/interview-prof-ould-abdeslam-koordinator-projekts\/#primaryimage"},"image":{"@id":"https:\/\/www.asimute.uha.fr\/de\/2025\/02\/11\/interview-prof-ould-abdeslam-koordinator-projekts\/#primaryimage"},"thumbnailUrl":"https:\/\/www.asimute.uha.fr\/de\/wp-content\/uploads\/2025\/02\/asimute-interview-djaffar-ould-energie.webp","datePublished":"2025-02-11T08:24:14+00:00","dateModified":"2025-03-17T08:37:20+00:00","breadcrumb":{"@id":"https:\/\/www.asimute.uha.fr\/de\/2025\/02\/11\/interview-prof-ould-abdeslam-koordinator-projekts\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asimute.uha.fr\/de\/2025\/02\/11\/interview-prof-ould-abdeslam-koordinator-projekts\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.asimute.uha.fr\/de\/2025\/02\/11\/interview-prof-ould-abdeslam-koordinator-projekts\/#primaryimage","url":"https:\/\/www.asimute.uha.fr\/de\/wp-content\/uploads\/2025\/02\/asimute-interview-djaffar-ould-energie.webp","contentUrl":"https:\/\/www.asimute.uha.fr\/de\/wp-content\/uploads\/2025\/02\/asimute-interview-djaffar-ould-energie.webp","width":750,"height":430},{"@type":"BreadcrumbList","@id":"https:\/\/www.asimute.uha.fr\/de\/2025\/02\/11\/interview-prof-ould-abdeslam-koordinator-projekts\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.asimute.uha.fr\/de\/"},{"@type":"ListItem","position":2,"name":"Interview mit Prof. Ould-Abdeslam &#8211; Koordinator des ASIMUTE-Projekts"}]},{"@type":"WebSite","@id":"https:\/\/www.asimute.uha.fr\/de\/#website","url":"https:\/\/www.asimute.uha.fr\/de\/","name":"ASIMUTE - Universit\u00e9 de Haute-Alsace","description":"","publisher":{"@id":"https:\/\/www.asimute.uha.fr\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asimute.uha.fr\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.asimute.uha.fr\/de\/#organization","name":"ASIMUTE - Universit\u00e9 de Haute-Alsace","url":"https:\/\/www.asimute.uha.fr\/de\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.asimute.uha.fr\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.asimute.uha.fr\/de\/wp-content\/uploads\/2024\/05\/Asimute-logo-site2.png","contentUrl":"https:\/\/www.asimute.uha.fr\/de\/wp-content\/uploads\/2024\/05\/Asimute-logo-site2.png","width":313,"height":100,"caption":"ASIMUTE - Universit\u00e9 de Haute-Alsace"},"image":{"@id":"https:\/\/www.asimute.uha.fr\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.asimute.uha.fr\/de\/#\/schema\/person\/b03aa6996efd8db50669100bf05ba2a1","name":"J.","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/9747a37e258302eedadb3a6cf028e96dd42bb3c11dc640aae55e16b9fb5d4d04?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9747a37e258302eedadb3a6cf028e96dd42bb3c11dc640aae55e16b9fb5d4d04?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9747a37e258302eedadb3a6cf028e96dd42bb3c11dc640aae55e16b9fb5d4d04?s=96&d=mm&r=g","caption":"J."},"url":"https:\/\/www.asimute.uha.fr\/de\/author\/jerrold-robertuha-fr\/"}]}},"_links":{"self":[{"href":"https:\/\/www.asimute.uha.fr\/de\/wp-json\/wp\/v2\/posts\/1519","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.asimute.uha.fr\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asimute.uha.fr\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asimute.uha.fr\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asimute.uha.fr\/de\/wp-json\/wp\/v2\/comments?post=1519"}],"version-history":[{"count":58,"href":"https:\/\/www.asimute.uha.fr\/de\/wp-json\/wp\/v2\/posts\/1519\/revisions"}],"predecessor-version":[{"id":1744,"href":"https:\/\/www.asimute.uha.fr\/de\/wp-json\/wp\/v2\/posts\/1519\/revisions\/1744"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asimute.uha.fr\/de\/wp-json\/wp\/v2\/media\/1539"}],"wp:attachment":[{"href":"https:\/\/www.asimute.uha.fr\/de\/wp-json\/wp\/v2\/media?parent=1519"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asimute.uha.fr\/de\/wp-json\/wp\/v2\/categories?post=1519"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asimute.uha.fr\/de\/wp-json\/wp\/v2\/tags?post=1519"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}