{"id":892,"date":"2024-05-31T08:51:07","date_gmt":"2024-05-31T06:51:07","guid":{"rendered":"https:\/\/www.asimute.uha.fr\/de\/?p=892"},"modified":"2024-06-04T08:16:25","modified_gmt":"2024-06-04T06:16:25","slug":"erforschung-und-vorschlag-zur-harmonisierung-des-rechtlichen-rahmens-fur-eigenverbrauch-in-deutschland-frankreich-und-der-schweiz","status":"publish","type":"post","link":"https:\/\/www.asimute.uha.fr\/de\/2024\/05\/31\/erforschung-und-vorschlag-zur-harmonisierung-des-rechtlichen-rahmens-fur-eigenverbrauch-in-deutschland-frankreich-und-der-schweiz\/","title":{"rendered":"Erforschung und Vorschlag zur Harmonisierung des rechtlichen Rahmens f\u00fcr Eigenverbrauch in Deutschland, Frankreich und der Schweiz"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"892\" class=\"elementor elementor-892\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-479860f7 e-flex e-con-boxed e-con e-parent\" data-id=\"479860f7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2352b421 elementor-widget elementor-widget-global elementor-global-53 elementor-widget-breadcrumbs\" data-id=\"2352b421\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p id=\"breadcrumbs\"><span><span><a href=\"https:\/\/www.asimute.uha.fr\/de\/\">Accueil<\/a><\/span><\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7ce28200 e-flex e-con-boxed e-con e-parent\" data-id=\"7ce28200\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-26f300d6 elementor-widget elementor-widget-menu-anchor\" data-id=\"26f300d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"haut-de-page\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4276f08 elementor-widget__width-initial WP-Categorie elementor-widget elementor-widget-heading\" data-id=\"4276f08\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Work package 6<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6721418a elementor-widget elementor-widget-heading\" data-id=\"6721418a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span class=\"elementor-heading-title elementor-size-default\">Forschung koordiniert durch Hochschule Kehl<\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4304eeff elementor-share-buttons--view-icon elementor-share-buttons--color-custom elementor-share-buttons--skin-minimal elementor-share-buttons--shape-square elementor-grid-0 elementor-widget elementor-widget-share-buttons\" data-id=\"4304eeff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"share-buttons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_facebook\" role=\"button\" tabindex=\"0\" aria-label=\"Partager sur facebook\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_twitter\" role=\"button\" tabindex=\"0\" aria-label=\"Partager sur twitter\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-twitter\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M459.37 151.716c.325 4.548.325 9.097.325 13.645 0 138.72-105.583 298.558-298.558 298.558-59.452 0-114.68-17.219-161.137-47.106 8.447.974 16.568 1.299 25.34 1.299 49.055 0 94.213-16.568 130.274-44.832-46.132-.975-84.792-31.188-98.112-72.772 6.498.974 12.995 1.624 19.818 1.624 9.421 0 18.843-1.3 27.614-3.573-48.081-9.747-84.143-51.98-84.143-102.985v-1.299c13.969 7.797 30.214 12.67 47.431 13.319-28.264-18.843-46.781-51.005-46.781-87.391 0-19.492 5.197-37.36 14.294-52.954 51.655 63.675 129.3 105.258 216.365 109.807-1.624-7.797-2.599-15.918-2.599-24.04 0-57.828 46.782-104.934 104.934-104.934 30.213 0 57.502 12.67 76.67 33.137 23.715-4.548 46.456-13.32 66.599-25.34-7.798 24.366-24.366 44.833-46.132 57.827 21.117-2.273 41.584-8.122 60.426-16.243-14.292 20.791-32.161 39.308-52.628 54.253z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_linkedin\" role=\"button\" tabindex=\"0\" aria-label=\"Partager sur linkedin\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-linkedin\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 32H31.9C14.3 32 0 46.5 0 64.3v383.4C0 465.5 14.3 480 31.9 480H416c17.6 0 32-14.5 32-32.3V64.3c0-17.8-14.4-32.3-32-32.3zM135.4 416H69V202.2h66.5V416zm-33.2-243c-21.3 0-38.5-17.3-38.5-38.5S80.9 96 102.2 96c21.2 0 38.5 17.3 38.5 38.5 0 21.3-17.2 38.5-38.5 38.5zm282.1 243h-66.4V312c0-24.8-.5-56.7-34.5-56.7-34.6 0-39.9 27-39.9 54.9V416h-66.4V202.2h63.7v29.2h.9c8.9-16.8 30.6-34.5 62.9-34.5 67.2 0 79.7 44.3 79.7 101.9V416z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-75c74515 elementor-widget elementor-widget-theme-post-featured-image elementor-widget-image\" data-id=\"75c74515\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"theme-post-featured-image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1000\" height=\"400\" src=\"https:\/\/www.asimute.uha.fr\/de\/wp-content\/uploads\/2024\/05\/cadre-juridique-harmonsiation-Asimute-Kehl.jpg\" class=\"attachment-full size-full wp-image-342\" alt=\"\" srcset=\"https:\/\/www.asimute.uha.fr\/de\/wp-content\/uploads\/2024\/05\/cadre-juridique-harmonsiation-Asimute-Kehl.jpg 1000w, https:\/\/www.asimute.uha.fr\/de\/wp-content\/uploads\/2024\/05\/cadre-juridique-harmonsiation-Asimute-Kehl-300x120.jpg 300w, https:\/\/www.asimute.uha.fr\/de\/wp-content\/uploads\/2024\/05\/cadre-juridique-harmonsiation-Asimute-Kehl-768x307.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-37839254 e-con-full e-flex e-con e-child\" data-id=\"37839254\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4880bb19 elementor-widget elementor-widget-global elementor-global-867 elementor-widget-post-navigation\" data-id=\"4880bb19\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-navigation.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-post-navigation\" role=\"navigation\" aria-label=\"Navigation de publication\">\n\t\t\t<div class=\"elementor-post-navigation__prev elementor-post-navigation__link\">\n\t\t\t\t<a href=\"https:\/\/www.asimute.uha.fr\/de\/2024\/05\/31\/beratungsinstrument-fur-die-energieplanung\/\" rel=\"prev\"><span class=\"post-navigation__arrow-wrapper post-navigation__arrow-prev\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-left\" viewBox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M31.7 239l136-136c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9L127.9 256l96.4 96.4c9.4 9.4 9.4 24.6 0 33.9L201.7 409c-9.4 9.4-24.6 9.4-33.9 0l-136-136c-9.5-9.4-9.5-24.6-.1-34z\"><\/path><\/svg><span class=\"elementor-screen-only\">Pr\u00e9c\u00e9dent<\/span><\/span><span class=\"elementor-post-navigation__link__prev\"><span class=\"post-navigation__prev--label\">Vorherige WP<\/span><\/span><\/a>\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-post-navigation__next elementor-post-navigation__link\">\n\t\t\t\t<a href=\"https:\/\/www.asimute.uha.fr\/de\/2024\/05\/31\/online-designtool-fur-bidirektionale-fahrzeugsysteme-in-privathaushalten\/\" rel=\"next\"><span class=\"elementor-post-navigation__link__next\"><span class=\"post-navigation__next--label\">N\u00e4chstes WP<\/span><\/span><span class=\"post-navigation__arrow-wrapper post-navigation__arrow-next\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-right\" viewBox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg><span class=\"elementor-screen-only\">Suivant<\/span><\/span><\/a>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1808913d text-zone elementor-widget elementor-widget-text-editor\" data-id=\"1808913d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div id=\"lipsum\"><p>Die Hochschule Kehl ist f\u00fcr die rechtlichen und administrativen Aspekte des Projekts zust\u00e4ndig. Diese juristische Unterst\u00fctzung des Projekts erstreckt sich \u00fcber die gesamte Laufzeit. Das Energie- und Eigenverbrauchsrecht ist sehr komplex und unterliegt zahlreichen \u00c4nderungen. Um die Entwicklung und die praktische Umsetzung des ASIMUTE-Projekts zu erm\u00f6glichen, ist es zum einen notwendig, das in jedem Land geltende Recht, die rechtlichen Rahmenbedingungen und die spezifischen Hindernisse zu ermitteln, und zum anderen die rechtlichen M\u00f6glichkeiten f\u00fcr eine grenz\u00fcberschreitende Zusammenarbeit zu analysieren bzw. L\u00f6sungen vorzuschlagen, wenn diese noch nicht vorhanden sind.<\/p><p>Der rechtliche Rahmen f\u00fcr Energie, von der Erzeugung \u00fcber die Speicherung und den Verbrauch bis hin zum Transport, ist sehr dynamisch und entwickelt sich st\u00e4ndig weiter. Die Europ\u00e4ische Union spielt bei der Energiepolitik und -gesetzgebung in Frankreich und Deutschland eine vorherrschende und wichtige Rolle. Dies zeigt sich insbesondere an der Richtlinie f\u00fcr erneuerbare Energien (RED III), die vor kurzem ge\u00e4ndert wurde und die diese beiden L\u00e4nder in ihr nationales Recht \u00fcbernehmen m\u00fcssen. Obwohl die Schweiz nicht Teil der Europ\u00e4ischen Un-ion ist, ist sie aufgrund des Handelsaustauschs und der grenz\u00fcberschreitenden Zusammenarbeit gezwungen, den rechtlichen Rahmen der Europ\u00e4ischen Union zu ber\u00fccksichtigen. Ziel unserer Arbeit wird es daher zun\u00e4chst sein, rechtliche Fragen und aktuelle rechtliche L\u00f6sungen zu identi-fizieren. Dazu geh\u00f6rt eine Analyse des bestehenden Rechts in Deutschland, Frankreich und der Schweiz. Anschlie\u00dfend werden wir versuchen, rechtliche L\u00f6sungen zu entwickeln, um die Sys-teme zu harmonisieren und eine bessere Zusammenarbeit zwischen den Partnern zu f\u00f6rdern. Dar\u00fcber hinaus stehen wir anderen Partnern zur Verf\u00fcgung, um alle Fragen zu kl\u00e4ren, auf die sie w\u00e4hrend des Projekts sto\u00dfen.<\/p><p>Um dies zu erreichen, beginnen wir mit wissenschaftlichen Recherchen in der Fachliteratur. Anhand der juristischen Literatur und der Rechtsprechung der beteiligten L\u00e4nder werden wir die aktuelle rechtliche Lage des Stromeigenverbrauchs darstellen k\u00f6nnen. Um den Praxisbezug zu wahren und unsere Punkte zu veranschaulichen, werden wir in jedem der teilnehmenden L\u00e4nder nach bestehenden Projekten suchen und die Akteure und Macher dieser Projekte befragen. Ziel unserer Interviews wird es sein, welche juristischen Aspekte in der Praxis sich vom Projektentwurf bis zur Projektdurchf\u00fchrung gestellt haben. Aus all dem werden wir feststellen k\u00f6n-nen, wo Handlungsbedarf f\u00fcr die Entwicklung des Stromeigenverbrauchs besteht. Au\u00dferdem werden wir analysieren, welche Unterschiede sich zwischen den verschiedenen L\u00e4ndern ergeben und dementsprechend welcher Harmonisierungsbedarf besteht, um die grenz\u00fcberschreitende Zusammenarbeit voranzubringen. Im Anschluss daran werden wir Berichte verfassen, um die Ergebnisse unserer Forschung darzustellen.<\/p><p>Die rechtliche Analyse, die wir f\u00fcr ein konkretes Projekt erstellen wollen, steht in v\u00f6lliger Synergie und Symbiose mit den anderen Arbeitspaketen, da sie darauf abzielt, die durch die prak-tischen Aspekte des Projekts aufgeworfenen rechtlichen Fragen zu beantworten.<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a65381b e-con-full e-flex e-con e-child\" data-id=\"a65381b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-735d206 e-con-full e-flex e-con e-child\" data-id=\"735d206\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-26380bf elementor-widget elementor-widget-image\" data-id=\"26380bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"153\" src=\"https:\/\/www.asimute.uha.fr\/de\/wp-content\/uploads\/2024\/05\/Logo-Kehl-University-Projet-Asimute.png\" class=\"attachment-featured-thumbnail size-featured-thumbnail wp-image-536\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3f78e8d e-con-full e-flex e-con e-child\" data-id=\"3f78e8d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2061590 elementor-widget elementor-widget-text-editor\" data-id=\"2061590\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 500;\">Hochschule Kehl<\/span><\/p><p>Kinzigallee 1<\/p><p>77694 Kehl<\/p><p>Deutschland<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-76649b8 elementor-position-inline-start elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-icon-box\" data-id=\"76649b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"https:\/\/www.hs-kehl.de\/\" target=\"_blank\" rel=\"nofollow\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Internetseite\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-university\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M496 128v16a8 8 0 0 1-8 8h-24v12c0 6.627-5.373 12-12 12H60c-6.627 0-12-5.373-12-12v-12H24a8 8 0 0 1-8-8v-16a8 8 0 0 1 4.941-7.392l232-88a7.996 7.996 0 0 1 6.118 0l232 88A8 8 0 0 1 496 128zm-24 304H40c-13.255 0-24 10.745-24 24v16a8 8 0 0 0 8 8h464a8 8 0 0 0 8-8v-16c0-13.255-10.745-24-24-24zM96 192v192H60c-6.627 0-12 5.373-12 12v20h416v-20c0-6.627-5.373-12-12-12h-36V192h-64v192h-64V192h-64v192h-64V192H96z\"><\/path><\/svg>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.hs-kehl.de\/\" target=\"_blank\" rel=\"nofollow\" >\n\t\t\t\t\t\t\tInternetseite\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/span>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b1c3f9b elementor-share-buttons--view-icon elementor-share-buttons--color-custom elementor-share-buttons--skin-minimal elementor-hidden-widescreen elementor-hidden-desktop elementor-hidden-laptop elementor-hidden-tablet_extra elementor-hidden-tablet elementor-hidden-mobile elementor-share-buttons--shape-square elementor-grid-0 elementor-widget elementor-widget-share-buttons\" data-id=\"7b1c3f9b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"share-buttons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_facebook\" role=\"button\" tabindex=\"0\" aria-label=\"Partager sur facebook\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_twitter\" role=\"button\" tabindex=\"0\" aria-label=\"Partager sur twitter\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-twitter\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M459.37 151.716c.325 4.548.325 9.097.325 13.645 0 138.72-105.583 298.558-298.558 298.558-59.452 0-114.68-17.219-161.137-47.106 8.447.974 16.568 1.299 25.34 1.299 49.055 0 94.213-16.568 130.274-44.832-46.132-.975-84.792-31.188-98.112-72.772 6.498.974 12.995 1.624 19.818 1.624 9.421 0 18.843-1.3 27.614-3.573-48.081-9.747-84.143-51.98-84.143-102.985v-1.299c13.969 7.797 30.214 12.67 47.431 13.319-28.264-18.843-46.781-51.005-46.781-87.391 0-19.492 5.197-37.36 14.294-52.954 51.655 63.675 129.3 105.258 216.365 109.807-1.624-7.797-2.599-15.918-2.599-24.04 0-57.828 46.782-104.934 104.934-104.934 30.213 0 57.502 12.67 76.67 33.137 23.715-4.548 46.456-13.32 66.599-25.34-7.798 24.366-24.366 44.833-46.132 57.827 21.117-2.273 41.584-8.122 60.426-16.243-14.292 20.791-32.161 39.308-52.628 54.253z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_linkedin\" role=\"button\" tabindex=\"0\" aria-label=\"Partager sur linkedin\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-linkedin\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 32H31.9C14.3 32 0 46.5 0 64.3v383.4C0 465.5 14.3 480 31.9 480H416c17.6 0 32-14.5 32-32.3V64.3c0-17.8-14.4-32.3-32-32.3zM135.4 416H69V202.2h66.5V416zm-33.2-243c-21.3 0-38.5-17.3-38.5-38.5S80.9 96 102.2 96c21.2 0 38.5 17.3 38.5 38.5 0 21.3-17.2 38.5-38.5 38.5zm282.1 243h-66.4V312c0-24.8-.5-56.7-34.5-56.7-34.6 0-39.9 27-39.9 54.9V416h-66.4V202.2h63.7v29.2h.9c8.9-16.8 30.6-34.5 62.9-34.5 67.2 0 79.7 44.3 79.7 101.9V416z\"><\/path><\/svg>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b02eb2e elementor-position-inline-start back elementor-mobile-position-inline-start elementor-view-default elementor-widget elementor-widget-global elementor-global-108 elementor-widget-icon-box\" data-id=\"1b02eb2e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"#haut-de-page\" class=\"elementor-icon\" tabindex=\"-1\" aria-label=\"Seitenanfang\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M177 159.7l136 136c9.4 9.4 9.4 24.6 0 33.9l-22.6 22.6c-9.4 9.4-24.6 9.4-33.9 0L160 255.9l-96.4 96.4c-9.4 9.4-24.6 9.4-33.9 0L7 329.7c-9.4-9.4-9.4-24.6 0-33.9l136-136c9.4-9.5 24.6-9.5 34-.1z\"><\/path><\/svg>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"#haut-de-page\" >\n\t\t\t\t\t\t\tSeitenanfang\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/span>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Die Hochschule Kehl ist f\u00fcr die rechtlichen und administrativen Aspekte des Projekts zust\u00e4ndig. Diese juristische Unterst\u00fctzung des Projekts erstreckt sich \u00fcber die gesamte Laufzeit. Das Energie- und Eigenverbrauchsrecht ist sehr komplex und unterliegt zahlreichen \u00c4nderungen. Um die Entwicklung und die praktische Umsetzung des ASIMUTE-Projekts zu erm\u00f6glichen, ist es zum einen notwendig, das in jedem Land [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":342,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9],"tags":[],"class_list":["post-892","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-work-package"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>WP6 - Erforschung und Vorschlag zur Harmonisierung des [...] - ASIMUTE - Universit\u00e9 de Haute-Alsace<\/title>\n<meta name=\"description\" content=\"Erfahren Sie mehr \u00fcber den von der Hochschule Kehl entwickelten wissenschaftlichen Ansatz, indem Sie eine Zusammenfassung des WP6 lesen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asimute.uha.fr\/de\/2024\/05\/31\/erforschung-und-vorschlag-zur-harmonisierung-des-rechtlichen-rahmens-fur-eigenverbrauch-in-deutschland-frankreich-und-der-schweiz\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"WP6 - Erforschung und Vorschlag zur Harmonisierung des [...] - ASIMUTE - Universit\u00e9 de Haute-Alsace\" \/>\n<meta property=\"og:description\" content=\"Erfahren Sie mehr \u00fcber den von der Hochschule Kehl entwickelten wissenschaftlichen Ansatz, indem Sie eine Zusammenfassung des WP6 lesen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asimute.uha.fr\/de\/2024\/05\/31\/erforschung-und-vorschlag-zur-harmonisierung-des-rechtlichen-rahmens-fur-eigenverbrauch-in-deutschland-frankreich-und-der-schweiz\/\" \/>\n<meta property=\"og:site_name\" content=\"ASIMUTE - Universit\u00e9 de Haute-Alsace\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-31T06:51:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-04T06:16:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.asimute.uha.fr\/de\/wp-content\/uploads\/2024\/05\/cadre-juridique-harmonsiation-Asimute-Kehl.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"J.\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"J.\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/2024\\\/05\\\/31\\\/erforschung-und-vorschlag-zur-harmonisierung-des-rechtlichen-rahmens-fur-eigenverbrauch-in-deutschland-frankreich-und-der-schweiz\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/2024\\\/05\\\/31\\\/erforschung-und-vorschlag-zur-harmonisierung-des-rechtlichen-rahmens-fur-eigenverbrauch-in-deutschland-frankreich-und-der-schweiz\\\/\"},\"author\":{\"name\":\"J.\",\"@id\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/#\\\/schema\\\/person\\\/b03aa6996efd8db50669100bf05ba2a1\"},\"headline\":\"Erforschung und Vorschlag zur Harmonisierung des rechtlichen Rahmens f\u00fcr Eigenverbrauch in Deutschland, Frankreich und der Schweiz\",\"datePublished\":\"2024-05-31T06:51:07+00:00\",\"dateModified\":\"2024-06-04T06:16:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/2024\\\/05\\\/31\\\/erforschung-und-vorschlag-zur-harmonisierung-des-rechtlichen-rahmens-fur-eigenverbrauch-in-deutschland-frankreich-und-der-schweiz\\\/\"},\"wordCount\":490,\"publisher\":{\"@id\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/2024\\\/05\\\/31\\\/erforschung-und-vorschlag-zur-harmonisierung-des-rechtlichen-rahmens-fur-eigenverbrauch-in-deutschland-frankreich-und-der-schweiz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cadre-juridique-harmonsiation-Asimute-Kehl.jpg\",\"articleSection\":[\"Work package\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/2024\\\/05\\\/31\\\/erforschung-und-vorschlag-zur-harmonisierung-des-rechtlichen-rahmens-fur-eigenverbrauch-in-deutschland-frankreich-und-der-schweiz\\\/\",\"url\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/2024\\\/05\\\/31\\\/erforschung-und-vorschlag-zur-harmonisierung-des-rechtlichen-rahmens-fur-eigenverbrauch-in-deutschland-frankreich-und-der-schweiz\\\/\",\"name\":\"WP6 - Erforschung und Vorschlag zur Harmonisierung des [...] - ASIMUTE - Universit\u00e9 de Haute-Alsace\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/2024\\\/05\\\/31\\\/erforschung-und-vorschlag-zur-harmonisierung-des-rechtlichen-rahmens-fur-eigenverbrauch-in-deutschland-frankreich-und-der-schweiz\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/2024\\\/05\\\/31\\\/erforschung-und-vorschlag-zur-harmonisierung-des-rechtlichen-rahmens-fur-eigenverbrauch-in-deutschland-frankreich-und-der-schweiz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cadre-juridique-harmonsiation-Asimute-Kehl.jpg\",\"datePublished\":\"2024-05-31T06:51:07+00:00\",\"dateModified\":\"2024-06-04T06:16:25+00:00\",\"description\":\"Erfahren Sie mehr \u00fcber den von der Hochschule Kehl entwickelten wissenschaftlichen Ansatz, indem Sie eine Zusammenfassung des WP6 lesen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/2024\\\/05\\\/31\\\/erforschung-und-vorschlag-zur-harmonisierung-des-rechtlichen-rahmens-fur-eigenverbrauch-in-deutschland-frankreich-und-der-schweiz\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/2024\\\/05\\\/31\\\/erforschung-und-vorschlag-zur-harmonisierung-des-rechtlichen-rahmens-fur-eigenverbrauch-in-deutschland-frankreich-und-der-schweiz\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/2024\\\/05\\\/31\\\/erforschung-und-vorschlag-zur-harmonisierung-des-rechtlichen-rahmens-fur-eigenverbrauch-in-deutschland-frankreich-und-der-schweiz\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cadre-juridique-harmonsiation-Asimute-Kehl.jpg\",\"contentUrl\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cadre-juridique-harmonsiation-Asimute-Kehl.jpg\",\"width\":1000,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/2024\\\/05\\\/31\\\/erforschung-und-vorschlag-zur-harmonisierung-des-rechtlichen-rahmens-fur-eigenverbrauch-in-deutschland-frankreich-und-der-schweiz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"WP6: Erforschung und Vorschlag zur Harmonisierung des (...)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/\",\"name\":\"ASIMUTE - Universit\u00e9 de Haute-Alsace\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/#organization\",\"name\":\"ASIMUTE - Universit\u00e9 de Haute-Alsace\",\"url\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Asimute-logo-site2.png\",\"contentUrl\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/Asimute-logo-site2.png\",\"width\":313,\"height\":100,\"caption\":\"ASIMUTE - Universit\u00e9 de Haute-Alsace\"},\"image\":{\"@id\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/#\\\/schema\\\/person\\\/b03aa6996efd8db50669100bf05ba2a1\",\"name\":\"J.\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9747a37e258302eedadb3a6cf028e96dd42bb3c11dc640aae55e16b9fb5d4d04?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9747a37e258302eedadb3a6cf028e96dd42bb3c11dc640aae55e16b9fb5d4d04?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/9747a37e258302eedadb3a6cf028e96dd42bb3c11dc640aae55e16b9fb5d4d04?s=96&d=mm&r=g\",\"caption\":\"J.\"},\"url\":\"https:\\\/\\\/www.asimute.uha.fr\\\/de\\\/author\\\/jerrold-robertuha-fr\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"WP6 - Erforschung und Vorschlag zur Harmonisierung des [...] - ASIMUTE - Universit\u00e9 de Haute-Alsace","description":"Erfahren Sie mehr \u00fcber den von der Hochschule Kehl entwickelten wissenschaftlichen Ansatz, indem Sie eine Zusammenfassung des WP6 lesen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asimute.uha.fr\/de\/2024\/05\/31\/erforschung-und-vorschlag-zur-harmonisierung-des-rechtlichen-rahmens-fur-eigenverbrauch-in-deutschland-frankreich-und-der-schweiz\/","og_locale":"fr_FR","og_type":"article","og_title":"WP6 - Erforschung und Vorschlag zur Harmonisierung des [...] - ASIMUTE - Universit\u00e9 de Haute-Alsace","og_description":"Erfahren Sie mehr \u00fcber den von der Hochschule Kehl entwickelten wissenschaftlichen Ansatz, indem Sie eine Zusammenfassung des WP6 lesen.","og_url":"https:\/\/www.asimute.uha.fr\/de\/2024\/05\/31\/erforschung-und-vorschlag-zur-harmonisierung-des-rechtlichen-rahmens-fur-eigenverbrauch-in-deutschland-frankreich-und-der-schweiz\/","og_site_name":"ASIMUTE - Universit\u00e9 de Haute-Alsace","article_published_time":"2024-05-31T06:51:07+00:00","article_modified_time":"2024-06-04T06:16:25+00:00","og_image":[{"width":1000,"height":400,"url":"https:\/\/www.asimute.uha.fr\/de\/wp-content\/uploads\/2024\/05\/cadre-juridique-harmonsiation-Asimute-Kehl.jpg","type":"image\/jpeg"}],"author":"J.","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"J.","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.asimute.uha.fr\/de\/2024\/05\/31\/erforschung-und-vorschlag-zur-harmonisierung-des-rechtlichen-rahmens-fur-eigenverbrauch-in-deutschland-frankreich-und-der-schweiz\/#article","isPartOf":{"@id":"https:\/\/www.asimute.uha.fr\/de\/2024\/05\/31\/erforschung-und-vorschlag-zur-harmonisierung-des-rechtlichen-rahmens-fur-eigenverbrauch-in-deutschland-frankreich-und-der-schweiz\/"},"author":{"name":"J.","@id":"https:\/\/www.asimute.uha.fr\/de\/#\/schema\/person\/b03aa6996efd8db50669100bf05ba2a1"},"headline":"Erforschung und Vorschlag zur Harmonisierung des rechtlichen Rahmens f\u00fcr Eigenverbrauch in Deutschland, Frankreich und der Schweiz","datePublished":"2024-05-31T06:51:07+00:00","dateModified":"2024-06-04T06:16:25+00:00","mainEntityOfPage":{"@id":"https:\/\/www.asimute.uha.fr\/de\/2024\/05\/31\/erforschung-und-vorschlag-zur-harmonisierung-des-rechtlichen-rahmens-fur-eigenverbrauch-in-deutschland-frankreich-und-der-schweiz\/"},"wordCount":490,"publisher":{"@id":"https:\/\/www.asimute.uha.fr\/de\/#organization"},"image":{"@id":"https:\/\/www.asimute.uha.fr\/de\/2024\/05\/31\/erforschung-und-vorschlag-zur-harmonisierung-des-rechtlichen-rahmens-fur-eigenverbrauch-in-deutschland-frankreich-und-der-schweiz\/#primaryimage"},"thumbnailUrl":"https:\/\/www.asimute.uha.fr\/de\/wp-content\/uploads\/2024\/05\/cadre-juridique-harmonsiation-Asimute-Kehl.jpg","articleSection":["Work package"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.asimute.uha.fr\/de\/2024\/05\/31\/erforschung-und-vorschlag-zur-harmonisierung-des-rechtlichen-rahmens-fur-eigenverbrauch-in-deutschland-frankreich-und-der-schweiz\/","url":"https:\/\/www.asimute.uha.fr\/de\/2024\/05\/31\/erforschung-und-vorschlag-zur-harmonisierung-des-rechtlichen-rahmens-fur-eigenverbrauch-in-deutschland-frankreich-und-der-schweiz\/","name":"WP6 - Erforschung und Vorschlag zur Harmonisierung des [...] - ASIMUTE - Universit\u00e9 de Haute-Alsace","isPartOf":{"@id":"https:\/\/www.asimute.uha.fr\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.asimute.uha.fr\/de\/2024\/05\/31\/erforschung-und-vorschlag-zur-harmonisierung-des-rechtlichen-rahmens-fur-eigenverbrauch-in-deutschland-frankreich-und-der-schweiz\/#primaryimage"},"image":{"@id":"https:\/\/www.asimute.uha.fr\/de\/2024\/05\/31\/erforschung-und-vorschlag-zur-harmonisierung-des-rechtlichen-rahmens-fur-eigenverbrauch-in-deutschland-frankreich-und-der-schweiz\/#primaryimage"},"thumbnailUrl":"https:\/\/www.asimute.uha.fr\/de\/wp-content\/uploads\/2024\/05\/cadre-juridique-harmonsiation-Asimute-Kehl.jpg","datePublished":"2024-05-31T06:51:07+00:00","dateModified":"2024-06-04T06:16:25+00:00","description":"Erfahren Sie mehr \u00fcber den von der Hochschule Kehl entwickelten wissenschaftlichen Ansatz, indem Sie eine Zusammenfassung des WP6 lesen.","breadcrumb":{"@id":"https:\/\/www.asimute.uha.fr\/de\/2024\/05\/31\/erforschung-und-vorschlag-zur-harmonisierung-des-rechtlichen-rahmens-fur-eigenverbrauch-in-deutschland-frankreich-und-der-schweiz\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asimute.uha.fr\/de\/2024\/05\/31\/erforschung-und-vorschlag-zur-harmonisierung-des-rechtlichen-rahmens-fur-eigenverbrauch-in-deutschland-frankreich-und-der-schweiz\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.asimute.uha.fr\/de\/2024\/05\/31\/erforschung-und-vorschlag-zur-harmonisierung-des-rechtlichen-rahmens-fur-eigenverbrauch-in-deutschland-frankreich-und-der-schweiz\/#primaryimage","url":"https:\/\/www.asimute.uha.fr\/de\/wp-content\/uploads\/2024\/05\/cadre-juridique-harmonsiation-Asimute-Kehl.jpg","contentUrl":"https:\/\/www.asimute.uha.fr\/de\/wp-content\/uploads\/2024\/05\/cadre-juridique-harmonsiation-Asimute-Kehl.jpg","width":1000,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.asimute.uha.fr\/de\/2024\/05\/31\/erforschung-und-vorschlag-zur-harmonisierung-des-rechtlichen-rahmens-fur-eigenverbrauch-in-deutschland-frankreich-und-der-schweiz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.asimute.uha.fr\/de\/"},{"@type":"ListItem","position":2,"name":"WP6: Erforschung und Vorschlag zur Harmonisierung des (...)"}]},{"@type":"WebSite","@id":"https:\/\/www.asimute.uha.fr\/de\/#website","url":"https:\/\/www.asimute.uha.fr\/de\/","name":"ASIMUTE - Universit\u00e9 de Haute-Alsace","description":"","publisher":{"@id":"https:\/\/www.asimute.uha.fr\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asimute.uha.fr\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.asimute.uha.fr\/de\/#organization","name":"ASIMUTE - Universit\u00e9 de Haute-Alsace","url":"https:\/\/www.asimute.uha.fr\/de\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.asimute.uha.fr\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.asimute.uha.fr\/de\/wp-content\/uploads\/2024\/05\/Asimute-logo-site2.png","contentUrl":"https:\/\/www.asimute.uha.fr\/de\/wp-content\/uploads\/2024\/05\/Asimute-logo-site2.png","width":313,"height":100,"caption":"ASIMUTE - Universit\u00e9 de Haute-Alsace"},"image":{"@id":"https:\/\/www.asimute.uha.fr\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.asimute.uha.fr\/de\/#\/schema\/person\/b03aa6996efd8db50669100bf05ba2a1","name":"J.","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/9747a37e258302eedadb3a6cf028e96dd42bb3c11dc640aae55e16b9fb5d4d04?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9747a37e258302eedadb3a6cf028e96dd42bb3c11dc640aae55e16b9fb5d4d04?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9747a37e258302eedadb3a6cf028e96dd42bb3c11dc640aae55e16b9fb5d4d04?s=96&d=mm&r=g","caption":"J."},"url":"https:\/\/www.asimute.uha.fr\/de\/author\/jerrold-robertuha-fr\/"}]}},"_links":{"self":[{"href":"https:\/\/www.asimute.uha.fr\/de\/wp-json\/wp\/v2\/posts\/892","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.asimute.uha.fr\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asimute.uha.fr\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asimute.uha.fr\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asimute.uha.fr\/de\/wp-json\/wp\/v2\/comments?post=892"}],"version-history":[{"count":20,"href":"https:\/\/www.asimute.uha.fr\/de\/wp-json\/wp\/v2\/posts\/892\/revisions"}],"predecessor-version":[{"id":1082,"href":"https:\/\/www.asimute.uha.fr\/de\/wp-json\/wp\/v2\/posts\/892\/revisions\/1082"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.asimute.uha.fr\/de\/wp-json\/wp\/v2\/media\/342"}],"wp:attachment":[{"href":"https:\/\/www.asimute.uha.fr\/de\/wp-json\/wp\/v2\/media?parent=892"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asimute.uha.fr\/de\/wp-json\/wp\/v2\/categories?post=892"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asimute.uha.fr\/de\/wp-json\/wp\/v2\/tags?post=892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}